{"id":80,"date":"2021-10-06T10:12:58","date_gmt":"2021-10-06T10:12:58","guid":{"rendered":"https:\/\/brok.qodeinteractive.com\/?page_id=80"},"modified":"2026-02-04T16:01:58","modified_gmt":"2026-02-04T15:01:58","slug":"architecte-haute-savoie","status":"publish","type":"page","link":"https:\/\/dessein-architectes.com\/","title":{"rendered":"Main Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"80\" class=\"elementor elementor-80\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f37949 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"4f37949\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-26be4e1\" data-id=\"26be4e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49bf37d elementor-widget elementor-widget-brok_core_portfolio_slider\" data-id=\"49bf37d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"brok_core_portfolio_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-portfolio-slider-holder qodef--loading\">\n\t<div class=\"qodef-portfolio-slider-images swiper-container\" data-unique=\"612\">\n\t\t<div class=\"swiper-wrapper\">\n\t\t\t<div class=\"qodef-e qodef-grid-item swiper-slide qodef-pfs-image qodef-active-image\" data-order=\"0\">\n\t\t\t<div class=\"qodef-e-image\">\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1718\" src=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Base-Nautique-Sciez-LAC-architecture-8-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Base-Nautique-Sciez-LAC-architecture-8-scaled.jpg 2560w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Base-Nautique-Sciez-LAC-architecture-8-300x201.jpg 300w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Base-Nautique-Sciez-LAC-architecture-8-1024x687.jpg 1024w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Base-Nautique-Sciez-LAC-architecture-8-768x515.jpg 768w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Base-Nautique-Sciez-LAC-architecture-8-1536x1031.jpg 1536w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Base-Nautique-Sciez-LAC-architecture-8-2048x1374.jpg 2048w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Base-Nautique-Sciez-LAC-architecture-8-600x403.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t<\/div>\n\t\t<div class=\"qodef-m-content-holder\">\n\t\t<span itemprop=\"name\" class=\"qodef-pfs-title entry-title\">Future city buildings<\/span>\n\t\t<a class=\"qodef-shortcode qodef-m  qodef-button qodef-layout--filled  qodef-html--link\" href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-item\/future-city-buildings\/\" target=\"_blank\"  style=\"color: #fff\">\t<span class=\"qodef-bg-effect\" ><\/span>\t<span class=\"qodef-m-text\">\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"12px\" height=\"12px\" viewBox=\"0 0 12 12\" style=\"enable-background:new 0 0 12 12;\" xml:space=\"preserve\"><g><rect y=\"5\" width=\"12\" height=\"2\"\/><rect y=\"5\" transform=\"matrix(6.123234e-17 -1 1 6.123234e-17 0 12)\" width=\"12\" height=\"2\"\/><\/g><\/svg>\t\tview more\t<\/span><\/a>\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-grid-item swiper-slide qodef-pfs-image \" data-order=\"1\">\n\t\t\t<div class=\"qodef-e-image\">\n\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/DSC07853-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/DSC07853-scaled.jpg 2560w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/DSC07853-300x200.jpg 300w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/DSC07853-1024x683.jpg 1024w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/DSC07853-768x512.jpg 768w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/DSC07853-1536x1024.jpg 1536w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/DSC07853-2048x1365.jpg 2048w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/DSC07853-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t<\/div>\n\t\t<div class=\"qodef-m-content-holder\">\n\t\t<span itemprop=\"name\" class=\"qodef-pfs-title entry-title\">Minimal Home Design<\/span>\n\t\t<a class=\"qodef-shortcode qodef-m  qodef-button qodef-layout--filled  qodef-html--link\" href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-item\/minimal-home-design\/\" target=\"_blank\"  style=\"color: #fff\">\t<span class=\"qodef-bg-effect\" ><\/span>\t<span class=\"qodef-m-text\">\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"12px\" height=\"12px\" viewBox=\"0 0 12 12\" style=\"enable-background:new 0 0 12 12;\" xml:space=\"preserve\"><g><rect y=\"5\" width=\"12\" height=\"2\"\/><rect y=\"5\" transform=\"matrix(6.123234e-17 -1 1 6.123234e-17 0 12)\" width=\"12\" height=\"2\"\/><\/g><\/svg>\t\tview more\t<\/span><\/a>\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-grid-item swiper-slide qodef-pfs-image \" data-order=\"2\">\n\t\t\t<div class=\"qodef-e-image\">\n\t\t\t<img decoding=\"async\" width=\"1429\" height=\"941\" src=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Beatrice-Cafieri_Fabrice-David-Architecte_Embarcadere-dYvoireDSC1301-302-WEB-Convert-profil-Srvb-.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Beatrice-Cafieri_Fabrice-David-Architecte_Embarcadere-dYvoireDSC1301-302-WEB-Convert-profil-Srvb-.jpg 1429w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Beatrice-Cafieri_Fabrice-David-Architecte_Embarcadere-dYvoireDSC1301-302-WEB-Convert-profil-Srvb--300x198.jpg 300w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Beatrice-Cafieri_Fabrice-David-Architecte_Embarcadere-dYvoireDSC1301-302-WEB-Convert-profil-Srvb--1024x674.jpg 1024w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Beatrice-Cafieri_Fabrice-David-Architecte_Embarcadere-dYvoireDSC1301-302-WEB-Convert-profil-Srvb--768x506.jpg 768w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Beatrice-Cafieri_Fabrice-David-Architecte_Embarcadere-dYvoireDSC1301-302-WEB-Convert-profil-Srvb--600x395.jpg 600w\" sizes=\"(max-width: 1429px) 100vw, 1429px\" \/>\t\t<\/div>\n\t\t<div class=\"qodef-m-content-holder\">\n\t\t<span itemprop=\"name\" class=\"qodef-pfs-title entry-title\">Harmony of shapes<\/span>\n\t\t<a class=\"qodef-shortcode qodef-m  qodef-button qodef-layout--filled  qodef-html--link\" href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-item\/harmony-of-shapes\/\" target=\"_blank\"  style=\"color: #fff\">\t<span class=\"qodef-bg-effect\" ><\/span>\t<span class=\"qodef-m-text\">\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"12px\" height=\"12px\" viewBox=\"0 0 12 12\" style=\"enable-background:new 0 0 12 12;\" xml:space=\"preserve\"><g><rect y=\"5\" width=\"12\" height=\"2\"\/><rect y=\"5\" transform=\"matrix(6.123234e-17 -1 1 6.123234e-17 0 12)\" width=\"12\" height=\"2\"\/><\/g><\/svg>\t\tview more\t<\/span><\/a>\t<\/div>\n<\/div>\n\t\t<\/div>\n\t\t<div id=\"qodef-portfolio-slider-images-container\"><\/div>\n\t<\/div>\n\t<div class=\"qodef-portfolio-slider-info-items-outer\">\n\t\t<div class=\"qodef-portfolio-slider-info-items swiper-container\" data-options=\"{&quot;spaceBetween&quot;:10,&quot;mousewheel&quot;:true,&quot;speed&quot;:&quot;&quot;,&quot;speedAnimation&quot;:&quot;&quot;,&quot;slidesPerView&quot;:3,&quot;slidesPerView1024&quot;:1,&quot;slidesPerView680&quot;:1,&quot;slidesPerView480&quot;:1}\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\n<div class=\"qodef-e qodef-grid-item swiper-slide qodef-pfs-item swiper-slide-active\" data-index=\"0\">\n\t<span class=\"qodef-pfs-count\">01<\/span>\n\t<div class=\"qodef-pfs-title-holder\"><h5 itemprop=\"name\" class=\"qodef-pfs-title entry-title\">Future city buildings<\/h5><\/div>\n\t<div class=\"qodef-pfs-category-holder\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-e-category\" href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-category\/contemporary\/\">\n\t\t\t\t\tContemporary\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n<\/div>\n\n<div class=\"qodef-e qodef-grid-item swiper-slide qodef-pfs-item \" data-index=\"1\">\n\t<span class=\"qodef-pfs-count\">02<\/span>\n\t<div class=\"qodef-pfs-title-holder\"><h5 itemprop=\"name\" class=\"qodef-pfs-title entry-title\">Minimal Home Design<\/h5><\/div>\n\t<div class=\"qodef-pfs-category-holder\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-e-category\" href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-category\/contemporary\/\">\n\t\t\t\t\tContemporary\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n<\/div>\n\n<div class=\"qodef-e qodef-grid-item swiper-slide qodef-pfs-item \" data-index=\"2\">\n\t<span class=\"qodef-pfs-count\">03<\/span>\n\t<div class=\"qodef-pfs-title-holder\"><h5 itemprop=\"name\" class=\"qodef-pfs-title entry-title\">Harmony of shapes<\/h5><\/div>\n\t<div class=\"qodef-pfs-category-holder\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-e-category\" href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-category\/contemporary\/\">\n\t\t\t\t\tContemporary\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"qodef--preloader\">\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-81ff27c qodef-elementor-content-grid elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"81ff27c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f27ecdf\" data-id=\"f27ecdf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6960543 elementor-widget elementor-widget-brok_core_section_title\" data-id=\"6960543\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"brok_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left \">\n\t\t<h2 class=\"qodef-m-title\" >\n\t\t\t\t\tOver 20 years<br \/> in the game\t\t\t<\/h2>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5049f40 qodef-elementor-content-grid elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5049f40\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c17f00d\" data-id=\"c17f00d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d43707a elementor-widget elementor-widget-brok_core_section_title\" data-id=\"d43707a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"brok_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left \">\n\t\t<h5 class=\"qodef-m-title\" >\n\t\t\t\t\tA propos\t\t\t<\/h5>\n\t\t<p class=\"qodef-m-text\" >L&#039;agence DESSEIN ARCHITECTES nait de l&#039;association entre Fabrice DAVID et Marion BRIERE, tous deux architectes DE. Apr\u00e8s avoir pass\u00e9 de nombreuses ann\u00e9es \u00e0 travailler ensemble c&#039;est avec cette nouvelle agence qu&#039;ils souhaitent continuer d&#039;\u00e9laborer des projets contemporains. Leur volont\u00e9 est de r\u00e9aliser une grande vari\u00e9t\u00e9 de projets et d&#039;\u00eatre \u00e0 m\u00eame de toujours apprendre de cette diversit\u00e9 architecturale.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3982bde\" data-id=\"3982bde\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0584bff elementor-widget elementor-widget-brok_core_section_title\" data-id=\"0584bff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"brok_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left \">\n\t\t<h5 class=\"qodef-m-title\" >\n\t\t\t\t\tAbout us\t\t\t<\/h5>\n\t\t<p class=\"qodef-m-text\" >The agency DESSEIN ARCHITECTES is born with the association between Fabrice DAVID and Marion BRIERE, both of them architects DE. After passing so many years to work together, it&#039;s with this new agency that they wish to continue to realized some contemporary projects. Their goal is to realize a big variety of projects and always be able to learn from this diversity.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-918e6ca\" data-id=\"918e6ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-091600b elementor-widget elementor-widget-brok_core_section_title\" data-id=\"091600b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"brok_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left \">\n\t\t<h5 class=\"qodef-m-title\" >\n\t\t\t\t\tOur goal\t\t\t<\/h5>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-316908a elementor-widget elementor-widget-text-editor\" data-id=\"316908a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Diffused the contemporary architecturale culture. Realized new projects and think outside the box !<\/p><p>Diffuser la culture architecturale contemporaine. Realiser de nouveaux projets et penser hors des sentiers battus.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-182d285 elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"182d285\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b7f09a\" data-id=\"7b7f09a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4615b0f elementor-widget elementor-widget-brok_core_portfolio_list\" data-id=\"4615b0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"brok_core_portfolio_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-portfolio-list qodef-item-layout--info-below   qodef-pl-appear-animation--yes qodef-grid qodef-layout--masonry  qodef-gutter--huge qodef-col-num--2 qodef-item-layout--info-below qodef--no-bottom-space qodef-pagination--off qodef-responsive--predefined qodef-swiper-pagination--on qodef-hover-animation--image-zoom\" data-options=\"{&quot;plugin&quot;:&quot;brok_core&quot;,&quot;module&quot;:&quot;post-types\\\/portfolio\\\/shortcodes&quot;,&quot;shortcode&quot;:&quot;portfolio-list&quot;,&quot;post_type&quot;:&quot;portfolio-item&quot;,&quot;next_page&quot;:&quot;2&quot;,&quot;max_pages_num&quot;:1,&quot;behavior&quot;:&quot;masonry&quot;,&quot;images_proportion&quot;:&quot;full&quot;,&quot;columns&quot;:&quot;2&quot;,&quot;columns_responsive&quot;:&quot;predefined&quot;,&quot;columns_1440&quot;:&quot;3&quot;,&quot;columns_1366&quot;:&quot;3&quot;,&quot;columns_1024&quot;:&quot;3&quot;,&quot;columns_768&quot;:&quot;3&quot;,&quot;columns_680&quot;:&quot;3&quot;,&quot;columns_480&quot;:&quot;3&quot;,&quot;space&quot;:&quot;huge&quot;,&quot;justified_gallery_last_row&quot;:&quot;nojustify&quot;,&quot;posts_per_page&quot;:&quot;6&quot;,&quot;orderby&quot;:&quot;date&quot;,&quot;order&quot;:&quot;ASC&quot;,&quot;additional_params&quot;:&quot;tax&quot;,&quot;tax&quot;:&quot;portfolio-category&quot;,&quot;tax_slug&quot;:&quot;structure&quot;,&quot;layout&quot;:&quot;info-below&quot;,&quot;hover_animation_info-below&quot;:&quot;image-zoom&quot;,&quot;hover_animation_info-follow&quot;:&quot;follow&quot;,&quot;title_tag&quot;:&quot;h5&quot;,&quot;hover_info&quot;:&quot;no&quot;,&quot;custom_margin&quot;:&quot;yes&quot;,&quot;appear_animation&quot;:&quot;yes&quot;,&quot;pagination_type&quot;:&quot;no-pagination&quot;,&quot;info_below_content_margin_top&quot;:&quot;24px&quot;,&quot;object_class_name&quot;:&quot;BrokCore_Portfolio_List_Shortcode&quot;,&quot;taxonomy_filter&quot;:&quot;portfolio-category&quot;,&quot;additional_query_args&quot;:{&quot;tax_query&quot;:[{&quot;taxonomy&quot;:&quot;portfolio-category&quot;,&quot;field&quot;:&quot;slug&quot;,&quot;terms&quot;:&quot;structure&quot;}]},&quot;space_value&quot;:40}\">\n\t\t<div class=\"qodef-grid-inner clear\">\n\t\t\t<div class=\"qodef-grid-masonry-sizer\"><\/div>\n\t<div class=\"qodef-grid-masonry-gutter\"><\/div>\n<article class=\"qodef-e qodef-grid-item qodef-custom-margin post-2946 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-structure portfolio-tag-villas\">\n\t<div class=\"qodef-e-inner\" style=\"margin: 0% 5.8% 0% 0%\">\n\t\t<div class=\"qodef-e-image\">\n\t\t\t\t<div class=\"qodef-e-media-image\">\n\t\t<a itemprop=\"url\" href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-item\/texture-combinations\/\" target=\"_self\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1534\" src=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Fabrice-David-La-Marketerie-85.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Fabrice-David-La-Marketerie-85.jpg 1024w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Fabrice-David-La-Marketerie-85-200x300.jpg 200w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Fabrice-David-La-Marketerie-85-684x1024.jpg 684w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Fabrice-David-La-Marketerie-85-768x1151.jpg 768w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Fabrice-David-La-Marketerie-85-600x899.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content\" style=\"margin-top:24px\">\n\t\t\t<div class=\"qodef-e-text\">\n\t\t\t\t<h5 itemprop=\"name\" class=\"qodef-e-title entry-title\" >\n\t<a itemprop=\"url\" class=\"qodef-e-title-link\" href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-item\/texture-combinations\/\" target=\"_self\">\n\t\tTexture Combinations &#8211; VILLA B\t<\/a>\n<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"qodef-e-bottom-holder\">\n\t\t\t\t<div class=\"qodef-e-info\">\n\t\t\t\t\t\t<a href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-category\/structure\/\" rel=\"tag\">Structure<\/a>\t<div class=\"qodef-info-separator-end\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/article>\n<article class=\"qodef-e qodef-grid-item qodef-custom-margin post-2949 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-structure portfolio-tag-public\">\n\t<div class=\"qodef-e-inner\" style=\"margin: 0% 0% 0% 5.8%\">\n\t\t<div class=\"qodef-e-image\">\n\t\t\t\t<div class=\"qodef-e-media-image\">\n\t\t<a itemprop=\"url\" href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-item\/deco-art\/\" target=\"_self\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/IMG_4223-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/IMG_4223-scaled.jpg 1920w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/IMG_4223-225x300.jpg 225w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/IMG_4223-768x1024.jpg 768w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/IMG_4223-1152x1536.jpg 1152w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/IMG_4223-1536x2048.jpg 1536w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/IMG_4223-600x800.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/a>\n\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content\" style=\"margin-top:24px\">\n\t\t\t<div class=\"qodef-e-text\">\n\t\t\t\t<h5 itemprop=\"name\" class=\"qodef-e-title entry-title\" >\n\t<a itemprop=\"url\" class=\"qodef-e-title-link\" href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-item\/deco-art\/\" target=\"_self\">\n\t\tB\u00e2timents tertiaires &#8211; LA SAT\t<\/a>\n<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"qodef-e-bottom-holder\">\n\t\t\t\t<div class=\"qodef-e-info\">\n\t\t\t\t\t\t<a href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-category\/structure\/\" rel=\"tag\">Structure<\/a>\t<div class=\"qodef-info-separator-end\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/article>\n<article class=\"qodef-e qodef-grid-item qodef-custom-margin post-2971 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-structure portfolio-tag-art\">\n\t<div class=\"qodef-e-inner\" style=\"margin: 5.7% 5.8% 0% 0%\">\n\t\t<div class=\"qodef-e-image\">\n\t\t\t\t<div class=\"qodef-e-media-image\">\n\t\t<a itemprop=\"url\" href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-item\/the-office\/\" target=\"_self\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1709\" height=\"2560\" src=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Yote-portrait-bureau-6-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Yote-portrait-bureau-6-scaled.jpg 1709w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Yote-portrait-bureau-6-200x300.jpg 200w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Yote-portrait-bureau-6-684x1024.jpg 684w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Yote-portrait-bureau-6-768x1150.jpg 768w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Yote-portrait-bureau-6-1025x1536.jpg 1025w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Yote-portrait-bureau-6-1367x2048.jpg 1367w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Yote-portrait-bureau-6-600x899.jpg 600w\" sizes=\"(max-width: 1709px) 100vw, 1709px\" \/>\t\t<\/a>\n\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content\" style=\"margin-top:24px\">\n\t\t\t<div class=\"qodef-e-text\">\n\t\t\t\t<h5 itemprop=\"name\" class=\"qodef-e-title entry-title\" >\n\t<a itemprop=\"url\" class=\"qodef-e-title-link\" href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-item\/the-office\/\" target=\"_self\">\n\t\tThe Office\t<\/a>\n<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"qodef-e-bottom-holder\">\n\t\t\t\t<div class=\"qodef-e-info\">\n\t\t\t\t\t\t<a href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-category\/structure\/\" rel=\"tag\">Structure<\/a>\t<div class=\"qodef-info-separator-end\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/article>\n<article class=\"qodef-e qodef-grid-item qodef-custom-margin post-2980 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-structure portfolio-tag-art\">\n\t<div class=\"qodef-e-inner\" style=\"margin: 5.7% 0% 0% 5.8%\">\n\t\t<div class=\"qodef-e-image\">\n\t\t\t\t<div class=\"qodef-e-media-image\">\n\t\t<a itemprop=\"url\" href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-item\/glamorous-stairs\/\" target=\"_self\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1701\" height=\"2560\" src=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Actives-Walker-030-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Actives-Walker-030-scaled.jpg 1701w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Actives-Walker-030-199x300.jpg 199w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Actives-Walker-030-681x1024.jpg 681w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Actives-Walker-030-768x1156.jpg 768w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Actives-Walker-030-1021x1536.jpg 1021w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Actives-Walker-030-1361x2048.jpg 1361w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Actives-Walker-030-600x903.jpg 600w\" sizes=\"(max-width: 1701px) 100vw, 1701px\" \/>\t\t<\/a>\n\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content\" style=\"margin-top:24px\">\n\t\t\t<div class=\"qodef-e-text\">\n\t\t\t\t<h5 itemprop=\"name\" class=\"qodef-e-title entry-title\" >\n\t<a itemprop=\"url\" class=\"qodef-e-title-link\" href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-item\/glamorous-stairs\/\" target=\"_self\">\n\t\tGlamorous Stairs &#8211; VILLA W\t<\/a>\n<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"qodef-e-bottom-holder\">\n\t\t\t\t<div class=\"qodef-e-info\">\n\t\t\t\t\t\t<a href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-category\/structure\/\" rel=\"tag\">Structure<\/a>\t<div class=\"qodef-info-separator-end\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/article>\n<article class=\"qodef-e qodef-grid-item qodef-custom-margin post-2983 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-structure portfolio-tag-art\">\n\t<div class=\"qodef-e-inner\" style=\"margin: 5.7% 5.8% 0% 0%\">\n\t\t<div class=\"qodef-e-image\">\n\t\t\t\t<div class=\"qodef-e-media-image\">\n\t\t<a itemprop=\"url\" href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-item\/white-art\/\" target=\"_self\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1534\" src=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/Fabrice-David-La-Marketerie-128.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/Fabrice-David-La-Marketerie-128.jpg 1024w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/Fabrice-David-La-Marketerie-128-200x300.jpg 200w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/Fabrice-David-La-Marketerie-128-684x1024.jpg 684w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/Fabrice-David-La-Marketerie-128-768x1151.jpg 768w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/Fabrice-David-La-Marketerie-128-600x899.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content\" style=\"margin-top:24px\">\n\t\t\t<div class=\"qodef-e-text\">\n\t\t\t\t<h5 itemprop=\"name\" class=\"qodef-e-title entry-title\" >\n\t<a itemprop=\"url\" class=\"qodef-e-title-link\" href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-item\/white-art\/\" target=\"_self\">\n\t\tWood Art &#8211; VILLA DE\t<\/a>\n<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"qodef-e-bottom-holder\">\n\t\t\t\t<div class=\"qodef-e-info\">\n\t\t\t\t\t\t<a href=\"https:\/\/dessein-architectes.com\/index.php\/portfolio-category\/structure\/\" rel=\"tag\">Structure<\/a>\t<div class=\"qodef-info-separator-end\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/article>\n\t<\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-803efae qodef-elementor-content-grid elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"803efae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1774bb5\" data-id=\"1774bb5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63e3dfe elementor-widget elementor-widget-brok_core_section_title\" data-id=\"63e3dfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"brok_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left \">\n\t\t<h2 class=\"qodef-m-title\" >\n\t\t\t\t\tOur team<br \/> of architects\t\t\t<\/h2>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7bb8aab qodef-elementor-content-grid elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7bb8aab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d8e184\" data-id=\"0d8e184\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01602ce elementor-widget elementor-widget-brok_core_team_list\" data-id=\"01602ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"brok_core_team_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-team-list qodef-item-layout--info-below qodef-grid qodef-layout--columns  qodef-gutter--large qodef-col-num--3 qodef-item-layout--info-below qodef--no-bottom-space qodef-pagination--off qodef-responsive--custom qodef-col-num--1440--3 qodef-col-num--1366--3 qodef-col-num--1024--2 qodef-col-num--768--2 qodef-col-num--680--1 qodef-col-num--480--1 qodef-swiper-pagination--on\" data-options=\"{&quot;plugin&quot;:&quot;brok_core&quot;,&quot;module&quot;:&quot;post-types\\\/team\\\/shortcodes&quot;,&quot;shortcode&quot;:&quot;team-list&quot;,&quot;post_type&quot;:&quot;team&quot;,&quot;next_page&quot;:&quot;2&quot;,&quot;max_pages_num&quot;:1,&quot;behavior&quot;:&quot;columns&quot;,&quot;images_proportion&quot;:&quot;brok_core_image_size_square&quot;,&quot;columns&quot;:&quot;3&quot;,&quot;columns_responsive&quot;:&quot;custom&quot;,&quot;columns_1440&quot;:&quot;3&quot;,&quot;columns_1366&quot;:&quot;3&quot;,&quot;columns_1024&quot;:&quot;2&quot;,&quot;columns_768&quot;:&quot;2&quot;,&quot;columns_680&quot;:&quot;1&quot;,&quot;columns_480&quot;:&quot;1&quot;,&quot;space&quot;:&quot;large&quot;,&quot;posts_per_page&quot;:&quot;4&quot;,&quot;orderby&quot;:&quot;date&quot;,&quot;order&quot;:&quot;ASC&quot;,&quot;additional_params&quot;:&quot;tax&quot;,&quot;tax&quot;:&quot;team-category&quot;,&quot;tax_slug&quot;:&quot;team&quot;,&quot;layout&quot;:&quot;info-below&quot;,&quot;title_tag&quot;:&quot;h5&quot;,&quot;pagination_type&quot;:&quot;no-pagination&quot;,&quot;object_class_name&quot;:&quot;BrokCore_Team_List_Shortcode&quot;,&quot;taxonomy_filter&quot;:&quot;team-category&quot;,&quot;additional_query_args&quot;:{&quot;tax_query&quot;:[{&quot;taxonomy&quot;:&quot;team-category&quot;,&quot;field&quot;:&quot;slug&quot;,&quot;terms&quot;:&quot;team&quot;}]},&quot;item_classes&quot;:&quot;qodef-e qodef-grid-item &quot;,&quot;space_value&quot;:25}\">\n\t\t<div class=\"qodef-grid-inner clear\">\n\t\t<div class=\"qodef-e qodef-grid-item  post-275 team type-team status-publish has-post-thumbnail hentry team-category-team\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-image\">\n\t\t\t\t<div class=\"qodef-e-media-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Fabrice-DAVID-650x650.jpg\" class=\"attachment-brok_core_image_size_square size-brok_core_image_size_square wp-post-image\" alt=\"\" srcset=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Fabrice-DAVID-650x650.jpg 650w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Fabrice-DAVID-300x300.jpg 300w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Fabrice-DAVID-1024x1022.jpg 1024w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Fabrice-DAVID-150x150.jpg 150w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Fabrice-DAVID-1536x1533.jpg 1536w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Fabrice-DAVID-2048x2044.jpg 2048w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Fabrice-DAVID-1300x1300.jpg 1300w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Fabrice-DAVID-600x599.jpg 600w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Fabrice-DAVID-100x100.jpg 100w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content\" >\n\t\t\t<h5 itemprop=\"name\" class=\"qodef-e-title entry-title\" >\n\t\t\tFabrice DAVID\t<\/h5>\n\t\t\t\t<p class=\"qodef-e-role\">Architect DPLG<\/p>\n\t\t\t\t\t\t\t<div class=\"qodef-team-member-social-icons\">\n\t\t\t\t\t\t\t<a class=\"qodef-team-member-social-icon\" href=\"https:\/\/www.instagram.com\/qodeinteractive\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"qodef-icon-font-awesome fab fa-instagram\" ><\/span>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"qodef-team-member-social-icon\" href=\"https:\/\/twitter.com\/qodeinteractive\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"qodef-icon-font-awesome fab fa-twitter\" ><\/span>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"qodef-team-member-social-icon\" href=\"https:\/\/www.facebook.com\/QodeInteractive\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"qodef-icon-font-awesome fab fa-facebook\" ><\/span>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-grid-item  post-279 team type-team status-publish has-post-thumbnail hentry team-category-team\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-image\">\n\t\t\t\t<div class=\"qodef-e-media-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Marion-BRIERE-650x650.jpg\" class=\"attachment-brok_core_image_size_square size-brok_core_image_size_square wp-post-image\" alt=\"\" srcset=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Marion-BRIERE-650x650.jpg 650w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Marion-BRIERE-150x150.jpg 150w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Marion-BRIERE-1300x1300.jpg 1300w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Marion-BRIERE-300x300.jpg 300w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Marion-BRIERE-100x100.jpg 100w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content\" >\n\t\t\t<h5 itemprop=\"name\" class=\"qodef-e-title entry-title\" >\n\t\t\tMarion BRIERE\t<\/h5>\n\t\t\t\t<p class=\"qodef-e-role\">Architecte HMONP<\/p>\n\t\t\t\t\t\t\t<div class=\"qodef-team-member-social-icons\">\n\t\t\t\t\t\t\t<a class=\"qodef-team-member-social-icon\" href=\"https:\/\/www.instagram.com\/qodeinteractive\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"qodef-icon-font-awesome fab fa-instagram\" ><\/span>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"qodef-team-member-social-icon\" href=\"https:\/\/twitter.com\/qodeinteractive\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"qodef-icon-font-awesome fab fa-twitter\" ><\/span>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"qodef-team-member-social-icon\" href=\"https:\/\/www.facebook.com\/QodeInteractive\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"qodef-icon-font-awesome fab fa-facebook\" ><\/span>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-grid-item  post-281 team type-team status-publish has-post-thumbnail hentry team-category-team\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-image\">\n\t\t\t\t<div class=\"qodef-e-media-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Emilie-DUNAND-650x650.jpg\" class=\"attachment-brok_core_image_size_square size-brok_core_image_size_square wp-post-image\" alt=\"\" srcset=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Emilie-DUNAND-650x650.jpg 650w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Emilie-DUNAND-300x300.jpg 300w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Emilie-DUNAND-1024x1024.jpg 1024w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Emilie-DUNAND-150x150.jpg 150w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Emilie-DUNAND-768x768.jpg 768w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Emilie-DUNAND-1536x1536.jpg 1536w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Emilie-DUNAND-2048x2048.jpg 2048w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Emilie-DUNAND-1300x1300.jpg 1300w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Emilie-DUNAND-600x600.jpg 600w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Photo-Emilie-DUNAND-100x100.jpg 100w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content\" >\n\t\t\t<h5 itemprop=\"name\" class=\"qodef-e-title entry-title\" >\n\t\t\tEmilie DUNAND\t<\/h5>\n\t\t\t\t<p class=\"qodef-e-role\">Architecte d'int\u00e9rieur<\/p>\n\t\t\t\t\t\t\t<div class=\"qodef-team-member-social-icons\">\n\t\t\t\t\t\t\t<a class=\"qodef-team-member-social-icon\" href=\"https:\/\/www.instagram.com\/qodeinteractive\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"qodef-icon-font-awesome fab fa-instagram\" ><\/span>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"qodef-team-member-social-icon\" href=\"https:\/\/twitter.com\/qodeinteractive\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"qodef-icon-font-awesome fab fa-twitter\" ><\/span>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"qodef-team-member-social-icon\" href=\"https:\/\/www.facebook.com\/QodeInteractive\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"qodef-icon-font-awesome fab fa-facebook\" ><\/span>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t<\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-544f3fc elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"544f3fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0da8636\" data-id=\"0da8636\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-195d0ef elementor-widget elementor-widget-brok_core_google_map\" data-id=\"195d0ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"brok_core_google_map.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-google-map\">\n\t<div class=\"qodef-m-map\" id=\"qodef-map-id--822\" data-addresses='[\"https:\/\/www.google.com\/maps\/place\/Jim+Fainberg\/@59.9117498,10.7816425,18z\/data=!4m13!1m7!3m6!1s0x46416e61f267f039:0x7e92605fd3231e9a!2z0J7RgdC70L4sINCd0L7RgNCy0LXRiNC60LA!3b1!8m2!3d59.9138688!4d10.7522454!3m4!1s0x46416e5774ade57f:0x29be5f61aa04b132!8m2!3d59.9125879!4d10.7816368\"]' data-pin=https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/12\/pin-map.png data-unique-id=822 data-height=670><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a96b5e qodef-elementor-content-grid elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a96b5e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b236b0\" data-id=\"1b236b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8233036 elementor-widget elementor-widget-brok_core_section_title\" data-id=\"8233036\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"brok_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left \">\n\t\t<h2 class=\"qodef-m-title\" >\n\t\t\t\t\tLatest news<br \/> and updates\t\t\t<\/h2>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-169e3a7 elementor-widget elementor-widget-brok_core_blog_list\" data-id=\"169e3a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"brok_core_blog_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-blog qodef-item-layout--simple qodef-grid qodef-layout--columns  qodef-gutter--large qodef-col-num--3 qodef-item-layout--simple qodef--no-bottom-space qodef-pagination--off qodef-responsive--custom qodef-col-num--1440--3 qodef-col-num--1366--3 qodef-col-num--1024--1 qodef-col-num--768--1 qodef-col-num--680--1 qodef-col-num--480--1 qodef-swiper-pagination--on\" data-options=\"{&quot;plugin&quot;:&quot;brok_core&quot;,&quot;module&quot;:&quot;blog\\\/shortcodes&quot;,&quot;shortcode&quot;:&quot;blog-list&quot;,&quot;post_type&quot;:&quot;post&quot;,&quot;next_page&quot;:&quot;2&quot;,&quot;max_pages_num&quot;:1,&quot;behavior&quot;:&quot;columns&quot;,&quot;images_proportion&quot;:&quot;full&quot;,&quot;columns&quot;:&quot;3&quot;,&quot;columns_responsive&quot;:&quot;custom&quot;,&quot;columns_1440&quot;:&quot;3&quot;,&quot;columns_1366&quot;:&quot;3&quot;,&quot;columns_1024&quot;:&quot;1&quot;,&quot;columns_768&quot;:&quot;1&quot;,&quot;columns_680&quot;:&quot;1&quot;,&quot;columns_480&quot;:&quot;1&quot;,&quot;space&quot;:&quot;large&quot;,&quot;justified_gallery_last_row&quot;:&quot;nojustify&quot;,&quot;posts_per_page&quot;:&quot;3&quot;,&quot;orderby&quot;:&quot;date&quot;,&quot;order&quot;:&quot;ASC&quot;,&quot;additional_params&quot;:&quot;tax&quot;,&quot;tax&quot;:&quot;category&quot;,&quot;tax_slug&quot;:&quot;lifestyle&quot;,&quot;layout&quot;:&quot;simple&quot;,&quot;title_tag&quot;:&quot;h4&quot;,&quot;excerpt_length&quot;:&quot;123&quot;,&quot;pagination_type&quot;:&quot;no-pagination&quot;,&quot;object_class_name&quot;:&quot;BrokCore_Blog_List_Shortcode&quot;,&quot;taxonomy_filter&quot;:&quot;category&quot;,&quot;additional_query_args&quot;:{&quot;tax_query&quot;:[{&quot;taxonomy&quot;:&quot;category&quot;,&quot;field&quot;:&quot;slug&quot;,&quot;terms&quot;:&quot;lifestyle&quot;}]},&quot;space_value&quot;:25}\">\n\t\t<div class=\"qodef-grid-inner clear\">\n\t\t<article class=\"qodef-e qodef-blog-item qodef-grid-item qodef-item--full post-522 post type-post status-publish format-standard has-post-thumbnail hentry category-lifestyle tag-art tag-inovative tag-public\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-image-wrapper\">\n\t\t\t<div class=\"qodef-e-media\">\n\t\t<div class=\"qodef-e-media-image\">\n\t\t<a itemprop=\"url\" href=\"https:\/\/dessein-architectes.com\/index.php\/2021\/10\/12\/extensions-of-media\/\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1141\" src=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Pers-route-Freinets-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Pers-route-Freinets-scaled.jpg 2560w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Pers-route-Freinets-300x134.jpg 300w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Pers-route-Freinets-1024x456.jpg 1024w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Pers-route-Freinets-768x342.jpg 768w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Pers-route-Freinets-1536x685.jpg 1536w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Pers-route-Freinets-2048x913.jpg 2048w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/Pers-route-Freinets-600x267.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t<\/a>\n\t<\/div>\n<\/div>\n<a title=\"Title Text: \" itemprop=\"dateCreated\" href=\"https:\/\/dessein-architectes.com\/index.php\/2021\/10\/\" class=\"entry-date \">\n\t<span class=\"qodef-date-day\">12<\/span>\n\t<span class=\"qodef-date-month\">Oct<\/span>\n<\/a><div class=\"qodef-info-separator-end\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content\">\n\t\t\t<div class=\"qodef-e-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-e-title entry-title\" >\n\t<a itemprop=\"url\" class=\"qodef-e-title-link\" href=\"https:\/\/dessein-architectes.com\/index.php\/2021\/10\/12\/extensions-of-media\/\">\n\t\tCentre culturel &#8211; Ch\u00e2tel\t<\/a>\n<\/h4>\n\t\t<p itemprop=\"description\" class=\"qodef-e-excerpt\">Le centre culturel de Ch\u00e2tel est un projet en cours dans lequel nous sommes en collaboration avec Wolf Architectes. Le pro<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"qodef-e-bottom-holder\">\n\t\t\t\t<div class=\"qodef-e-info\">\n\t\t\t\t\t\t<div class=\"qodef-e-read-more\">\n\t\t<a class=\"qodef-shortcode qodef-m  qodef-button qodef-layout--textual  qodef-html--link\" href=\"https:\/\/dessein-architectes.com\/index.php\/2021\/10\/12\/extensions-of-media\/\" target=\"_self\"  >\t\t<svg class=\"qodef-svg--pagination-arrow-right\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16.2px\"     height=\"9.6px\" viewBox=\"0 0 16.2 9.6\" style=\"enable-background:new 0 0 16.2 9.6;\" xml:space=\"preserve\"><g><line stroke-width=\"2\" stroke=\"currentColor\" x1=\"15.2\" y1=\"4.8\" x2=\"0\" y2=\"4.8\"\/><polyline fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" points=\"10.9,0.6 15,4.8 10.9,8.9\"\/><\/g><\/svg><\/a>\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/article>\n<article class=\"qodef-e qodef-blog-item qodef-grid-item qodef-item--full post-525 post type-post status-publish format-standard has-post-thumbnail hentry category-lifestyle tag-art tag-inovative tag-public\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-image-wrapper\">\n\t\t\t<div class=\"qodef-e-media\">\n\t\t<div class=\"qodef-e-media-image\">\n\t\t<a itemprop=\"url\" href=\"https:\/\/dessein-architectes.com\/index.php\/2021\/10\/12\/base-nautique-de-sciez-sur-leman-architecte\/\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/12\/1623234886891.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/12\/1623234886891.jpg 2048w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/12\/1623234886891-300x200.jpg 300w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/12\/1623234886891-1024x683.jpg 1024w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/12\/1623234886891-768x512.jpg 768w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/12\/1623234886891-1536x1024.jpg 1536w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/12\/1623234886891-600x400.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t<\/a>\n\t<\/div>\n<\/div>\n<a title=\"Title Text: \" itemprop=\"dateCreated\" href=\"https:\/\/dessein-architectes.com\/index.php\/2021\/10\/\" class=\"entry-date \">\n\t<span class=\"qodef-date-day\">12<\/span>\n\t<span class=\"qodef-date-month\">Oct<\/span>\n<\/a><div class=\"qodef-info-separator-end\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content\">\n\t\t\t<div class=\"qodef-e-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-e-title entry-title\" >\n\t<a itemprop=\"url\" class=\"qodef-e-title-link\" href=\"https:\/\/dessein-architectes.com\/index.php\/2021\/10\/12\/base-nautique-de-sciez-sur-leman-architecte\/\">\n\t\tBASE NAUTIQUE DE SCIEZ\t<\/a>\n<\/h4>\n\t\t<p itemprop=\"description\" class=\"qodef-e-excerpt\">Le b\u00e2timent est un dialogue constant entre l\u2019int\u00e9rieur et l\u2019ext\u00e9rieur. Divis\u00e9 en trois parties distinctes, il perme<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"qodef-e-bottom-holder\">\n\t\t\t\t<div class=\"qodef-e-info\">\n\t\t\t\t\t\t<div class=\"qodef-e-read-more\">\n\t\t<a class=\"qodef-shortcode qodef-m  qodef-button qodef-layout--textual  qodef-html--link\" href=\"https:\/\/dessein-architectes.com\/index.php\/2021\/10\/12\/base-nautique-de-sciez-sur-leman-architecte\/\" target=\"_self\"  >\t\t<svg class=\"qodef-svg--pagination-arrow-right\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16.2px\"     height=\"9.6px\" viewBox=\"0 0 16.2 9.6\" style=\"enable-background:new 0 0 16.2 9.6;\" xml:space=\"preserve\"><g><line stroke-width=\"2\" stroke=\"currentColor\" x1=\"15.2\" y1=\"4.8\" x2=\"0\" y2=\"4.8\"\/><polyline fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" points=\"10.9,0.6 15,4.8 10.9,8.9\"\/><\/g><\/svg><\/a>\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/article>\n<article class=\"qodef-e qodef-blog-item qodef-grid-item qodef-item--full post-533 post type-post status-publish format-standard has-post-thumbnail hentry category-lifestyle tag-art tag-inovative tag-public\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-image-wrapper\">\n\t\t\t<div class=\"qodef-e-media\">\n\t\t<div class=\"qodef-e-media-image\">\n\t\t<a itemprop=\"url\" href=\"https:\/\/dessein-architectes.com\/index.php\/2021\/10\/12\/gymnase-architecte-haute-savoie\/\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1450\" height=\"966\" src=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/PRN_5650_\u00a9_Studio_Erick_Saillet.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/PRN_5650_\u00a9_Studio_Erick_Saillet.jpg 1450w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/PRN_5650_\u00a9_Studio_Erick_Saillet-300x200.jpg 300w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/PRN_5650_\u00a9_Studio_Erick_Saillet-1024x682.jpg 1024w, https:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/10\/PRN_5650_\u00a9_Studio_Erick_Saillet-768x512.jpg 768w\" sizes=\"(max-width: 1450px) 100vw, 1450px\" \/>\t\t<\/a>\n\t<\/div>\n<\/div>\n<a title=\"Title Text: \" itemprop=\"dateCreated\" href=\"https:\/\/dessein-architectes.com\/index.php\/2021\/10\/\" class=\"entry-date \">\n\t<span class=\"qodef-date-day\">12<\/span>\n\t<span class=\"qodef-date-month\">Oct<\/span>\n<\/a><div class=\"qodef-info-separator-end\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content\">\n\t\t\t<div class=\"qodef-e-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-e-title entry-title\" >\n\t<a itemprop=\"url\" class=\"qodef-e-title-link\" href=\"https:\/\/dessein-architectes.com\/index.php\/2021\/10\/12\/gymnase-architecte-haute-savoie\/\">\n\t\tGYMNASE A CHAMBERY\t<\/a>\n<\/h4>\n\t\t<p itemprop=\"description\" class=\"qodef-e-excerpt\">Le projet concerne la r\u00e9alisation d\u2019un gymnase pour le coll\u00e8ge Saint Fran\u00e7ois de Sales. Au rez-de-chauss\u00e9e on retrouv<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"qodef-e-bottom-holder\">\n\t\t\t\t<div class=\"qodef-e-info\">\n\t\t\t\t\t\t<div class=\"qodef-e-read-more\">\n\t\t<a class=\"qodef-shortcode qodef-m  qodef-button qodef-layout--textual  qodef-html--link\" href=\"https:\/\/dessein-architectes.com\/index.php\/2021\/10\/12\/gymnase-architecte-haute-savoie\/\" target=\"_self\"  >\t\t<svg class=\"qodef-svg--pagination-arrow-right\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16.2px\"     height=\"9.6px\" viewBox=\"0 0 16.2 9.6\" style=\"enable-background:new 0 0 16.2 9.6;\" xml:space=\"preserve\"><g><line stroke-width=\"2\" stroke=\"currentColor\" x1=\"15.2\" y1=\"4.8\" x2=\"0\" y2=\"4.8\"\/><polyline fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" points=\"10.9,0.6 15,4.8 10.9,8.9\"\/><\/g><\/svg><\/a>\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/article>\n\t<\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Future city buildings view more Minimal Home Design view more Harmony of shapes view more 01 Future city buildings Contemporary 02 Minimal Home Design Contemporary 03 Harmony of shapes Contemporary Over 20 years in the game A propos L&#039;agence DESSEIN ARCHITECTES nait de l&#039;association entre Fabrice DAVID et Marion BRIERE, tous deux architectes DE. Apr\u00e8s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-full-width.php","meta":{"footnotes":""},"class_list":["post-80","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Main Home - Dessein Architectes<\/title>\n<meta name=\"description\" content=\"L&#039;agence d&#039;architecture DESSEIN ARCHITECTES est sp\u00e9cialis\u00e9e en architecture contemporaine. Situ\u00e9e \u00e0 Thonon-les-bains. Fran\u00e7ais \/ Anglais\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dessein-architectes.com\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Main Home - Dessein Architectes\" \/>\n<meta property=\"og:description\" content=\"L&#039;agence d&#039;architecture DESSEIN ARCHITECTES est sp\u00e9cialis\u00e9e en architecture contemporaine. Situ\u00e9e \u00e0 Thonon-les-bains. Fran\u00e7ais \/ Anglais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dessein-architectes.com\/\" \/>\n<meta property=\"og:site_name\" content=\"Dessein Architectes\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T15:01:58+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Base-Nautique-Sciez-LAC-architecture-8-scaled.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dessein-architectes.com\/\",\"url\":\"https:\/\/dessein-architectes.com\/\",\"name\":\"Main Home - Dessein Architectes\",\"isPartOf\":{\"@id\":\"https:\/\/dessein-architectes.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dessein-architectes.com\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dessein-architectes.com\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Base-Nautique-Sciez-LAC-architecture-8-scaled.jpg\",\"datePublished\":\"2021-10-06T10:12:58+00:00\",\"dateModified\":\"2026-02-04T15:01:58+00:00\",\"description\":\"L'agence d'architecture DESSEIN ARCHITECTES est sp\u00e9cialis\u00e9e en architecture contemporaine. Situ\u00e9e \u00e0 Thonon-les-bains. Fran\u00e7ais \/ Anglais\",\"breadcrumb\":{\"@id\":\"https:\/\/dessein-architectes.com\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dessein-architectes.com\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dessein-architectes.com\/#primaryimage\",\"url\":\"http:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Base-Nautique-Sciez-LAC-architecture-8-scaled.jpg\",\"contentUrl\":\"http:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Base-Nautique-Sciez-LAC-architecture-8-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dessein-architectes.com\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dessein-architectes.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Main Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dessein-architectes.com\/#website\",\"url\":\"https:\/\/dessein-architectes.com\/\",\"name\":\"Dessein Architectes\",\"description\":\"Dessein Architectes\",\"publisher\":{\"@id\":\"https:\/\/dessein-architectes.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dessein-architectes.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dessein-architectes.com\/#organization\",\"name\":\"Dessein Architectes\",\"url\":\"https:\/\/dessein-architectes.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dessein-architectes.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/cropped-cropped-LOGO-SEUL-NOIR.png\",\"contentUrl\":\"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/cropped-cropped-LOGO-SEUL-NOIR.png\",\"width\":512,\"height\":512,\"caption\":\"Dessein Architectes\"},\"image\":{\"@id\":\"https:\/\/dessein-architectes.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/dessein.architectes\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Main Home - Dessein Architectes","description":"L'agence d'architecture DESSEIN ARCHITECTES est sp\u00e9cialis\u00e9e en architecture contemporaine. Situ\u00e9e \u00e0 Thonon-les-bains. Fran\u00e7ais \/ Anglais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dessein-architectes.com\/","og_locale":"fr_FR","og_type":"article","og_title":"Main Home - Dessein Architectes","og_description":"L'agence d'architecture DESSEIN ARCHITECTES est sp\u00e9cialis\u00e9e en architecture contemporaine. Situ\u00e9e \u00e0 Thonon-les-bains. Fran\u00e7ais \/ Anglais","og_url":"https:\/\/dessein-architectes.com\/","og_site_name":"Dessein Architectes","article_modified_time":"2026-02-04T15:01:58+00:00","og_image":[{"url":"http:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Base-Nautique-Sciez-LAC-architecture-8-scaled.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dessein-architectes.com\/","url":"https:\/\/dessein-architectes.com\/","name":"Main Home - Dessein Architectes","isPartOf":{"@id":"https:\/\/dessein-architectes.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dessein-architectes.com\/#primaryimage"},"image":{"@id":"https:\/\/dessein-architectes.com\/#primaryimage"},"thumbnailUrl":"http:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Base-Nautique-Sciez-LAC-architecture-8-scaled.jpg","datePublished":"2021-10-06T10:12:58+00:00","dateModified":"2026-02-04T15:01:58+00:00","description":"L'agence d'architecture DESSEIN ARCHITECTES est sp\u00e9cialis\u00e9e en architecture contemporaine. Situ\u00e9e \u00e0 Thonon-les-bains. Fran\u00e7ais \/ Anglais","breadcrumb":{"@id":"https:\/\/dessein-architectes.com\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dessein-architectes.com\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dessein-architectes.com\/#primaryimage","url":"http:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Base-Nautique-Sciez-LAC-architecture-8-scaled.jpg","contentUrl":"http:\/\/dessein-architectes.com\/wp-content\/uploads\/2021\/11\/Base-Nautique-Sciez-LAC-architecture-8-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/dessein-architectes.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dessein-architectes.com\/"},{"@type":"ListItem","position":2,"name":"Main Home"}]},{"@type":"WebSite","@id":"https:\/\/dessein-architectes.com\/#website","url":"https:\/\/dessein-architectes.com\/","name":"Dessein Architectes","description":"Dessein Architectes","publisher":{"@id":"https:\/\/dessein-architectes.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dessein-architectes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dessein-architectes.com\/#organization","name":"Dessein Architectes","url":"https:\/\/dessein-architectes.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dessein-architectes.com\/#\/schema\/logo\/image\/","url":"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/cropped-cropped-LOGO-SEUL-NOIR.png","contentUrl":"https:\/\/dessein-architectes.com\/wp-content\/uploads\/2024\/09\/cropped-cropped-LOGO-SEUL-NOIR.png","width":512,"height":512,"caption":"Dessein Architectes"},"image":{"@id":"https:\/\/dessein-architectes.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/dessein.architectes\/"]}]}},"_links":{"self":[{"href":"https:\/\/dessein-architectes.com\/index.php\/wp-json\/wp\/v2\/pages\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dessein-architectes.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dessein-architectes.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dessein-architectes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dessein-architectes.com\/index.php\/wp-json\/wp\/v2\/comments?post=80"}],"version-history":[{"count":61,"href":"https:\/\/dessein-architectes.com\/index.php\/wp-json\/wp\/v2\/pages\/80\/revisions"}],"predecessor-version":[{"id":6240,"href":"https:\/\/dessein-architectes.com\/index.php\/wp-json\/wp\/v2\/pages\/80\/revisions\/6240"}],"wp:attachment":[{"href":"https:\/\/dessein-architectes.com\/index.php\/wp-json\/wp\/v2\/media?parent=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}